{"id":89623,"date":"2025-04-22T00:00:00","date_gmt":"2025-04-22T00:00:00","guid":{"rendered":"https:\/\/iumsonline.cloud\/2025\/04\/22\/%d8%a7%d8%aa%d8%ad%d8%a7%d8%af%db%8c%d9%87-%d9%88-%d8%af%d8%a7%d9%86%d8%b4%da%af%d8%a7%d9%87-%d8%b3%d9%84%d8%b7%d8%a7%d9%86-%d9%85%d8%ad%d9%85%d8%af-%d9%81%d8%a7%d8%aa%d8%ad-%d8%a7%d8%b2-%d9%87%d9%85\/"},"modified":"2025-04-22T00:00:00","modified_gmt":"2025-04-22T00:00:00","slug":"%d8%a7%d8%aa%d8%ad%d8%a7%d8%af%db%8c%d9%87-%d9%88-%d8%af%d8%a7%d9%86%d8%b4%da%af%d8%a7%d9%87-%d8%b3%d9%84%d8%b7%d8%a7%d9%86-%d9%85%d8%ad%d9%85%d8%af-%d9%81%d8%a7%d8%aa%d8%ad-%d8%a7%d8%b2-%d9%87%d9%85","status":"publish","type":"post","link":"https:\/\/iumsonline.org\/fa\/archives\/89623","title":{"rendered":"\u0627\u062a\u062d\u0627\u062f\u06cc\u0647 \u0648 \u062f\u0627\u0646\u0634\u06af\u0627\u0647 \u0633\u0644\u0637\u0627\u0646 \u0645\u062d\u0645\u062f \u0641\u0627\u062a\u062d \u0627\u0632 \u0647\u0645\u06a9\u0627\u0631\u06cc \u0639\u0644\u0645\u06cc \u0628\u0631\u0627\u06cc \u0628\u0631\u06af\u0632\u0627\u0631\u06cc \u0647\u0645\u0627\u06cc\u0634 \u00ab\u0641\u0642\u0647 \u0645\u0639\u06cc\u0627\u0631\u00bb \u062f\u0631 \u0698\u0648\u0626\u0646 \u0622\u06cc\u0646\u062f\u0647 \u062e\u0628\u0631 \u0645\u06cc\u200c\u062f\u0647\u0646\u062f"},"content":{"rendered":"<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><b><span lang=\"AR-SA\" style=\"font-size:22.0pt;\nline-height:115%;font-family:&quot;Sakkal Majalla&quot;;color:#C00000\">\u0627\u062a\u062d\u0627\u062f\u06cc\u0647 \u0648 \u062f\u0627\u0646\u0634\u06af\u0627\u0647 \u0633\u0644\u0637\u0627\u0646<br \/>\n\u0645\u062d\u0645\u062f \u0641\u0627\u062a\u062d \u0627\u0632 \u0647\u0645\u06a9\u0627\u0631\u06cc \u0639\u0644\u0645\u06cc \u0628\u0631\u0627\u06cc \u0628\u0631\u06af\u0632\u0627\u0631\u06cc \u0647\u0645\u0627\u06cc\u0634 \u00ab\u0641\u0642\u0647 \u0645\u0639\u06cc\u0627\u0631\u00bb \u062f\u0631 \u0698\u0648\u0626\u0646 \u0622\u06cc\u0646\u062f\u0647 \u062e\u0628\u0631 \u0645\u06cc\u200c\u062f\u0647\u0646\u062f<\/span><\/b><b><span dir=\"LTR\" style=\"font-size:22.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;;\ncolor:#C00000\"><o:p><\/o:p><\/span><\/b><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><span dir=\"LTR\" style=\"font-size:20.0pt;\nline-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><b><span lang=\"AR-SA\" style=\"font-size:20.0pt;\nline-height:115%;font-family:&quot;Sakkal Majalla&quot;;color:#0070C0\">\u0645\u0642\u062f\u0645\u0647:<\/span><\/b><b><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;;\ncolor:#0070C0\"><o:p><\/o:p><\/span><\/b><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><span lang=\"AR-SA\" style=\"font-size:20.0pt;\nline-height:115%;font-family:&quot;Sakkal Majalla&quot;\">\u0641\u0642\u0647 \u0645\u0639\u06cc\u0627\u0631 \u06cc\u06a9\u06cc \u0627\u0632 \u0627\u0631\u06a9\u0627\u0646 \u0627\u0633\u0627\u0633\u06cc \u0641\u0642\u0647<br \/>\n\u0627\u0633\u0644\u0627\u0645\u06cc \u0627\u0633\u062a\u061b \u0632\u06cc\u0631\u0627 \u0623\u0635\u0644 \u062a\u0639\u0627\u062f\u0644 \u0648\u0627\u0639\u062a\u062f\u0627\u0644 \u062f\u0631 \u0627\u062d\u06a9\u0627\u0645 \u0648 \u06a9\u0627\u0631\u0628\u0631\u062f\u0647\u0627\u06cc \u0639\u0645\u0644\u06cc \u0631\u0627 \u062f\u0631 \u0628\u0631 \u0645\u06cc\u200c\u06af\u06cc\u0631\u062f. \u0634\u0631\u06cc\u0639\u062a<br \/>\n\u0627\u0633\u0644\u0627\u0645 \u0628\u0647 \u062a\u0631\u0648\u06cc\u062c \u0639\u062f\u0627\u0644\u062a \u0648 \u0628\u0631\u0642\u0631\u0627\u0631\u06cc \u062a\u0631\u0627\u0632\u0648\u06cc \u0627\u0646\u0635\u0627\u0641 \u062f\u0631 \u0647\u0645\u0647 \u0627\u0628\u0639\u0627\u062f \u0632\u0646\u062f\u06af\u06cc \u0648 \u062a\u0636\u0645\u06cc\u0646 \u06cc\u06a9\u067e\u0627\u0631\u0686\u06af\u06cc<br \/>\n\u0648 \u0633\u0639\u0627\u062f\u062a \u0639\u0644\u0627\u0642\u0645\u0646\u062f \u0627\u0633\u062a.<\/span><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:\n115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><span lang=\"AR-SA\" style=\"font-size:20.0pt;\nline-height:115%;font-family:&quot;Sakkal Majalla&quot;\">\u062f\u06a9\u062a\u0631 \u0639\u0644\u06cc \u0645\u062d\u06cc\u200c\u0627\u0644\u062f\u06cc\u0646 \u0642\u0631\u0647 \u062f\u0627\u063a\u06cc \u0627\u0632 \u0637\u0631\u06cc\u0642<br \/>\n\u06a9\u062a\u0627\u0628 \u00ab\u0641\u0642\u0647 \u0645\u0639\u06cc\u0627\u0631\u00bb \u06a9\u0647 \u0628\u0647 \u0645\u0628\u0627\u0646\u06cc \u0641\u0642\u0647\u06cc \u0648 \u0645\u0642\u0627\u0635\u062f\u06cc \u0645\u06cc\u200c\u067e\u0631\u062f\u0627\u0632\u062f \u0648\u0641\u0647\u0645 \u0648 \u06a9\u0627\u0631\u0628\u0631\u062f \u0645\u062a\u0648\u0627\u0632\u0646 \u0631\u0627 \u062f\u0631<br \/>\n\u0647\u0631 \u062f\u0648 \u0633\u0637\u062d \u0641\u0631\u062f\u06cc \u0648 \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u062a\u0636\u0645\u06cc\u0646 \u0645\u06cc\u200c\u06a9\u0646\u062f\u060c \u062f\u0631 \u0627\u06cc\u0646 \u0631\u0627\u0633\u062a\u0627 \u0645\u0634\u0627\u0631\u06a9\u062a \u0639\u0644\u0645\u06cc \u0642\u0627\u0628\u0644\u200c\u062a\u0648\u062c\u0647\u06cc \u062f\u0627\u0634\u062a\u0647<br \/>\n\u0627\u0633\u062a. \u0628\u0627 \u0646\u06cc\u0627\u0632 \u0631\u0648\u0632\u0627\u0641\u0632\u0648\u0646 \u0628\u0647 \u0627\u062d\u06cc\u0627\u06cc \u0631\u0648\u06cc\u06a9\u0631\u062f \u0627\u0639\u062a\u062f\u0627\u0644 \u0648 \u0645\u06cc\u0627\u0646\u0647\u200c\u0631\u0648\u06cc \u062f\u0631 \u0627\u0646\u062f\u06cc\u0634\u0647 \u0627\u0633\u0644\u0627\u0645\u06cc\u060c \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628<br \/>\n\u0634\u0627\u0644\u0648\u062f\u0647 \u0639\u0644\u0645\u06cc \u062c\u062f\u06cc\u062f\u06cc \u0631\u0627 \u062a\u0634\u06a9\u06cc\u0644 \u0645\u06cc\u200c\u062f\u0647\u062f \u06a9\u0647 \u0627\u0641\u0642\u200c\u0647\u0627\u06cc \u0648\u0633\u06cc\u0639\u06cc \u0631\u0627 \u0628\u0631\u0627\u06cc \u0645\u0637\u0627\u0644\u0639\u0647 \u062f\u0631 \u0627\u06cc\u0646 \u0632\u0645\u06cc\u0646\u0647 \u0645\u06cc\u200c\u06af\u0634\u0627\u06cc\u062f.<\/span><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><span lang=\"AR-SA\" style=\"font-size:20.0pt;\nline-height:115%;font-family:&quot;Sakkal Majalla&quot;\">\u0627\u0632 \u0627\u06cc\u0646 \u0631\u0648\u060c \u0627\u06cc\u0646 \u06a9\u0646\u0641\u0631\u0627\u0646\u0633 \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u0628\u0633\u062a\u0631\u06cc<br \/>\n\u0639\u0644\u0645\u06cc \u0628\u0631\u0627\u06cc \u0628\u0631\u0631\u0633\u06cc \u00ab\u0641\u0642\u0647 \u0645\u0639\u06cc\u0627\u0631\u00bb \u0648\u0628\u062d\u062b \u062f\u0631 \u0645\u0648\u0631\u062f \u0627\u0628\u0639\u0627\u062f \u0641\u06a9\u0631\u06cc \u0648 \u0641\u0642\u0647\u06cc \u0648\u062a\u0648\u0633\u0639\u0647 \u0633\u0627\u0632\u0648\u06a9\u0627\u0631\u0647\u0627\u06cc \u0622\u0646<br \/>\n\u0628\u0631\u0627\u06cc \u0647\u0645\u06af\u0627\u0645\u06cc \u0628\u0627 \u0686\u0627\u0644\u0634\u200c\u0647\u0627\u06cc \u0645\u0639\u0627\u0635\u0631 \u0628\u0631\u06af\u0632\u0627\u0631 \u0645\u06cc\u200c\u0634\u0648\u062f. <o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><span dir=\"LTR\" style=\"font-size:20.0pt;\nline-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><b><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;;\ncolor:#0070C0\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>* \u0627\u0647\u062f\u0627\u0641 \u06a9\u0646\u0641\u0631\u0627\u0646\u0633:<\/span><\/b><b><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;;\ncolor:#0070C0\"><o:p><\/o:p><\/span><\/b><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><b><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>1-<\/span><\/b><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"> \u062a\u0639\u0631\u06cc\u0641 \u0645\u0641\u0647\u0648\u0645<br \/>\n\u0641\u0642\u0647 \u0645\u0639\u06cc\u0627\u0631\u060c \u0627\u0635\u0648\u0644 \u0648 \u0627\u0647\u0645\u06cc\u062a \u0622\u0646 \u062f\u0631 \u0641\u0647\u0645 \u0648\u0639\u0645\u0644.<\/span><span dir=\"LTR\" style=\"font-size:\n20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><b><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>2-<\/span><\/b><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"> \u062a\u062d\u0644\u06cc\u0644 \u0627\u0633\u0628\u0627\u0628<br \/>\n\u0646\u0627\u06a9\u0627\u0631\u0622\u0645\u062f\u06cc \u0645\u0648\u0627\u0632\u0646\u0647\u200c\u0647\u0627\u06cc \u0641\u0642\u0647\u06cc \u0648 \u0641\u06a9\u0631\u06cc \u062f\u0631 \u0639\u0635\u0631 \u062d\u0627\u0636\u0631.<\/span><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><b><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>3- <\/span><\/b><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\">\u062a\u0645\u0631\u06a9\u0632 \u0628\u0631<br \/>\n\u0631\u0627\u0647 \u062d\u0644\u200c\u0647\u0627\u06cc \u0627\u0633\u0644\u0627\u0645\u06cc \u0628\u0631\u0627\u06cc \u0686\u0627\u0644\u0634\u200c\u0647\u0627\u06cc \u0627\u062c\u062a\u0645\u0627\u0639\u06cc\u060c \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0648 \u0633\u06cc\u0627\u0633\u06cc \u0627\u0632 \u0645\u0646\u0638\u0631 \u0641\u0642\u0647 \u0645\u0639\u06cc\u0627\u0631.<\/span><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><b><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>4-<\/span><\/b><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"> \u062a\u0631\u0648\u06cc\u062c \u0627\u0639\u062a\u062f\u0627\u0644<br \/>\n\u0648 \u0645\u06cc\u0627\u0646\u0647\u200c\u0631\u0648\u06cc \u062f\u0631 \u06af\u0641\u062a\u0645\u0627\u0646 \u0645\u0639\u0627\u0635\u0631 \u0627\u0633\u0644\u0627\u0645\u06cc.<\/span><span dir=\"LTR\" style=\"font-size:20.0pt;\nline-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><b><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>5-<\/span><\/b><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"> \u062a\u0634\u0648\u06cc\u0642 \u0628\u0647<br \/>\n\u067e\u0698\u0648\u0647\u0634 \u0639\u0644\u0645\u06cc \u062f\u0631 \u0632\u0645\u06cc\u0646\u0647 \u0645\u0628\u0627\u0646\u06cc \u0641\u0642\u0647\u06cc \u0645\u0639\u06cc\u0627\u0631 \u062f\u0631 \u0634\u0631\u06cc\u0639\u062a. <o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><span dir=\"LTR\" style=\"font-size:20.0pt;\nline-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><b><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;;\ncolor:#0070C0\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>* \u0645\u0648\u0636\u0648\u0639\u0627\u062a \u06a9\u0646\u0641\u0631\u0627\u0646\u0633:<\/span><\/b><b><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;;\ncolor:#0070C0\"><o:p><\/o:p><\/span><\/b><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><b><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;;\ncolor:#002060\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>&#8211; \u0645\u062d\u0648\u0631 \u0627\u0648\u0644: \u0645\u0628\u0627\u0646\u06cc \u0648 \u0646\u0638\u0631\u06cc\u0647\u200c\u067e\u0631\u062f\u0627\u0632\u06cc<br \/>\n\u0641\u0642\u0647 \u0645\u0639\u06cc\u0627\u0631:<\/span><\/b><b><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;\nfont-family:&quot;Sakkal Majalla&quot;;color:#002060\"><o:p><\/o:p><\/span><\/b><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>\u2022 \u0631\u06cc\u0634\u0647\u200c\u0647\u0627\u06cc \u062a\u0627\u0631\u06cc\u062e\u06cc \u0648 \u0645\u0628\u0646\u0627\u06cc \u062d\u0642\u0648\u0642\u06cc \u0645\u0641\u0647\u0648\u0645 \u0645\u0639\u06cc\u0627\u0631.<\/span><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>\u2022 \u062a\u0639\u0627\u062f\u0644 \u0628\u06cc\u0646 \u0627\u0647\u062f\u0627\u0641 \u0634\u0631\u06cc\u0639\u062a \u0627\u0633\u0644\u0627\u0645\u06cc \u0648 \u0645\u062a\u0648\u0646 \u062c\u0632\u0626\u06cc.<\/span><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>\u2022 \u0645\u0648\u0627\u0632\u0646\u0647 \u062f\u0631 \u0642\u0648\u0627\u0639\u062f \u0641\u0642\u0647\u06cc \u0648 \u0645\u0628\u0627\u0646\u06cc \u0634\u0631\u0639\u06cc.<\/span><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><b><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;;\ncolor:#002060\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>&#8211; \u0645\u062d\u0648\u0631 \u062f\u0648\u0645: \u0641\u0642\u0647 \u0645\u0639\u06cc\u0627\u0631 \u062f\u0631<br \/>\n\u0633\u0646\u062a \u0648 \u0633\u06cc\u0631\u0647 \u067e\u06cc\u0627\u0645\u0628\u0631 \u0627\u06a9\u0631\u0645<\/span><\/b><b><span dir=\"LTR\" style=\"font-size:20.0pt;\nline-height:115%;font-family:&quot;Sakkal Majalla&quot;;color:#002060\"><o:p><\/o:p><\/span><\/b><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>\u2022 \u067e\u06cc\u0627\u0645\u0628\u0631 \u0627\u06a9\u0631\u0645 \u0646\u0645\u0648\u0646\u0647 \u0628\u0627\u0631\u0632 \u062a\u0639\u0627\u062f\u0644 \u062f\u0631 \u0632\u0646\u062f\u06af\u06cc \u0648 \u0639\u0645\u0644\u06a9\u0631\u062f.<\/span><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>\u2022 \u06a9\u0627\u0631\u0628\u0631\u062f\u0647\u0627\u06cc \u0641\u0642\u0647 \u0645\u0639\u06cc\u0627\u0631 \u062f\u0631 \u0641\u062a\u0627\u0648\u0627\u06cc \u062e\u0644\u0641\u0627\u06cc \u0631\u0627\u0634\u062f\u06cc\u0646.<\/span><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><b><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;;\ncolor:#002060\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>&#8211; \u0645\u062d\u0648\u0631 \u0633\u0648\u0645: \u062a\u0639\u0627\u062f\u0644 \u062f\u0631 \u0627\u0639\u062a\u0642\u0627\u062f\u0627\u062a\u060c<br \/>\n\u0639\u0628\u0627\u062f\u0627\u062a \u0648\u0645\u0639\u0627\u0645\u0644\u0627\u062a<\/span><\/b><b><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:\n115%;font-family:&quot;Sakkal Majalla&quot;;color:#002060\"><o:p><\/o:p><\/span><\/b><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>\u2022 \u062a\u0639\u0627\u062f\u0644 \u0628\u06cc\u0646 \u0627\u06cc\u0645\u0627\u0646 \u0648\u0639\u0642\u0644\u0627\u0646\u06cc\u062a \u062f\u0631 \u0627\u0646\u062f\u06cc\u0634\u0647 \u0627\u0633\u0644\u0627\u0645\u06cc.<\/span><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>\u2022 \u062a\u0639\u0627\u062f\u0644 \u0628\u06cc\u0646 \u0639\u0628\u0627\u062f\u0627\u062a \u0648\u0622\u062f\u0627\u0628 \u0648\u0631\u0633\u0648\u0645.<\/span><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>\u2022 \u0627\u0642\u062a\u0635\u0627\u062f \u0648\u0645\u0639\u0627\u0645\u0644\u0627\u062a \u0645\u0627\u0644\u06cc \u0627\u0632 \u0646\u0638\u0631 \u0641\u0642\u0647 \u0645\u0639\u06cc\u0627\u0631. <\/span><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><b><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;;\ncolor:#002060\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>&#8211; \u0645\u062d\u0648\u0631 \u0686\u0647\u0627\u0631\u0645: \u062a\u0623\u062b\u06cc\u0631 \u0645\u0639\u06cc\u0627\u0631<br \/>\n\u0628\u0631 \u0627\u0646\u062f\u06cc\u0634\u0647 \u0646\u0648\u06cc\u0646 \u0627\u0633\u0644\u0627\u0645\u06cc<\/span><\/b><b><span dir=\"LTR\" style=\"font-size:20.0pt;\nline-height:115%;font-family:&quot;Sakkal Majalla&quot;;color:#002060\"><o:p><\/o:p><\/span><\/b><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>\u2022 \u062a\u0639\u0627\u062f\u0644 \u062f\u0631 \u0645\u0633\u0627\u0626\u0644 \u0622\u0632\u0627\u062f\u06cc\u200c\u0647\u0627 \u0648\u062d\u0642\u0648\u0642 \u0628\u0634\u0631.<\/span><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>\u2022 \u062a\u0639\u0627\u062f\u0644 \u0628\u06cc\u0646 \u0627\u062c\u062a\u0647\u0627\u062f \u0648 \u062a\u0642\u0644\u06cc\u062f \u062f\u0631 \u0641\u0642\u0647 \u0645\u0639\u0627\u0635\u0631.<\/span><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>\u2022 \u0646\u0642\u0634 \u0641\u0642\u0647 \u0645\u0639\u06cc\u0627\u0631 \u062f\u0631 \u062a\u062c\u062f\u06cc\u062f \u06af\u0641\u062a\u0645\u0627\u0646 \u062f\u06cc\u0646\u06cc.<\/span><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><b><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;;\ncolor:#002060\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>&#8211; \u0645\u062d\u0648\u0631 \u067e\u0646\u062c\u0645: \u062f\u0631\u062e\u0648\u0627\u0633\u062a \u062a\u062f\u0648\u06cc\u0646<br \/>\n\u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f\u0647\u0627\u06cc \u062c\u062f\u06cc\u062f<\/span><\/b><b><span dir=\"LTR\" style=\"font-size:20.0pt;\nline-height:115%;font-family:&quot;Sakkal Majalla&quot;;color:#002060\"><o:p><\/o:p><\/span><\/b><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>\u2022 \u062a\u0648\u0633\u0639\u0647 \u0641\u0642\u0647 \u0645\u0639\u06cc\u0627\u0631 \u0628\u0631\u0627\u06cc \u0647\u0645\u06af\u0627\u0645\u06cc \u0628\u0627 \u0686\u0627\u0644\u0634\u200c\u0647\u0627\u06cc \u0645\u0639\u0627\u0635\u0631.<\/span><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>\u2022 \u0646\u0642\u0634 \u062f\u0627\u0646\u0634\u06af\u0627\u0647\u06cc\u0627\u0646 \u0648 \u067e\u0698\u0648\u0647\u0634\u06af\u0631\u0627\u0646 \u062f\u0631 \u06af\u0633\u062a\u0631\u0634 \u062f\u0627\u0645\u0646\u0647<br \/>\n\u0645\u0639\u06cc\u0627\u0631 \u0628\u0647 \u0645\u0648\u0636\u0648\u0639\u0627\u062a \u0645\u062f\u0631\u0646. <\/span><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:\n115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"unicode-bidi: embed;\"><b><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:\n&quot;Sakkal Majalla&quot;;color:#0070C0\">&nbsp;<\/span><\/b><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"unicode-bidi: embed;\"><b><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:\n&quot;Sakkal Majalla&quot;;color:#0070C0\">* \u0645\u062e\u0627\u0637\u0628\u0627\u0646 \u0647\u0645\u0627\u06cc\u0634:<\/span><\/b><b><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;;\ncolor:#0070C0\"><o:p><\/o:p><\/span><\/b><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>\u2022 \u0639\u0644\u0645\u0627 \u0648 \u0627\u0646\u062f\u06cc\u0634\u0645\u0646\u062f\u0627\u0646 \u0639\u0644\u0648\u0645 \u0627\u0633\u0644\u0627\u0645\u06cc.<\/span><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>\u2022 \u062f\u0627\u0646\u0634\u06af\u0627\u0647\u06cc\u0627\u0646 \u0648 \u067e\u0698\u0648\u0647\u0634\u06af\u0631\u0627\u0646 \u0641\u0642\u0647 \u0627\u0633\u0644\u0627\u0645\u06cc.<\/span><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>\u2022 \u0645\u0633\u0624\u0648\u0644\u0627\u0646 \u0646\u0647\u0627\u062f\u0647\u0627\u06cc \u0645\u0630\u0647\u0628\u06cc \u0648 \u0633\u06cc\u0627\u0633\u06cc.<\/span><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>\u2022 \u067e\u0698\u0648\u0647\u0634\u06af\u0631\u0627\u0646 \u0645\u0633\u0627\u0626\u0644 \u062d\u0642\u0648\u0642\u06cc \u0648 \u0627\u062c\u062a\u0645\u0627\u0639\u06cc.<\/span><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>\u2022 \u062f\u0627\u0646\u0634\u062c\u0648\u06cc\u0627\u0646 \u0648 \u062f\u0627\u0646\u0634\u200c\u067e\u0698\u0648\u0647\u0627\u0646 \u062f\u0627\u0646\u0634\u06af\u0627\u0647\u200c\u0647\u0627\u06cc \u0627\u0633\u0644\u0627\u0645\u06cc.<\/span><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"unicode-bidi: embed;\"><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><b><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;;\ncolor:#0070C0\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>* \u0628\u0631\u0646\u0627\u0645\u0647\u200c\u0647\u0627\u06cc \u06a9\u0646\u0641\u0631\u0627\u0646\u0633:<\/span><\/b><b><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;;\ncolor:#0070C0\"><o:p><\/o:p><\/span><\/b><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>\u2022 \u062c\u0644\u0633\u0627\u062a \u067e\u0698\u0648\u0647\u0634\u06cc \u0628\u0631\u0627\u06cc \u0628\u0631\u0631\u0633\u06cc \u0645\u0642\u0627\u0644\u0627\u062a \u0639\u0644\u0645\u06cc \u0627\u0631\u0633\u0627\u0644\u06cc.<\/span><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>\u2022 \u0633\u0645\u06cc\u0646\u0627\u0631\u0647\u0627\u06cc \u06af\u0641\u062a\u06af\u0648\u06cc \u0628\u06cc\u0646 \u0639\u0644\u0645\u0627 \u0648 \u0627\u0646\u062f\u06cc\u0634\u0645\u0646\u062f\u0627\u0646.<\/span><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>\u2022 \u06a9\u0627\u0631\u06af\u0627\u0647\u200c\u0647\u0627\u06cc \u06a9\u0627\u0631\u0628\u0631\u062f\u06cc \u0628\u062d\u062b \u0648 \u0628\u0631\u0631\u0633\u06cc \u0645\u0648\u0627\u0632\u06cc\u0646 \u0641\u0642\u0647<br \/>\n\u0627\u0633\u0644\u0627\u0645\u06cc \u062f\u0631 \u0645\u0633\u0627\u0626\u0644 \u0645\u0639\u0627\u0635\u0631. <\/span><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:\n115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"unicode-bidi: embed;\"><b><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:\n&quot;Sakkal Majalla&quot;;color:#0070C0\">&nbsp;<\/span><\/b><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"unicode-bidi: embed;\"><b><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:\n&quot;Sakkal Majalla&quot;;color:#0070C0\">* \u0632\u0645\u0627\u0646 \u0648 \u0645\u06a9\u0627\u0646:<\/span><\/b><b><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;;\ncolor:#0070C0\"><o:p><\/o:p><\/span><\/b><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>\u2022 \u062a\u0627\u0631\u06cc\u062e: 21-22 \u0698\u0648\u0626\u0646 2025.<\/span><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>\u2022 \u0645\u06a9\u0627\u0646: \u0627\u0633\u062a\u0627\u0646\u0628\u0648\u0644 &#8211; \u062a\u0631\u06a9\u06cc\u0647.<\/span><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"unicode-bidi: embed;\"><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><b><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;;\ncolor:#0070C0\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>* \u0646\u062a\u0627\u06cc\u062c \u0645\u0648\u0631\u062f \u0627\u0646\u062a\u0638\u0627\u0631 \u06a9\u0646\u0641\u0631\u0627\u0646\u0633:<\/span><\/b><b><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;;\ncolor:#0070C0\"><o:p><\/o:p><\/span><\/b><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>\u2022 \u0627\u0631\u0627\u0626\u0647 \u062f\u06cc\u062f\u06af\u0627\u0647\u200c\u0647\u0627\u06cc \u0631\u0648\u0634\u0646 \u062f\u0631 \u0645\u0648\u0631\u062f \u0686\u06af\u0648\u0646\u06af\u06cc \u062f\u0633\u062a\u06cc\u0627\u0628\u06cc<br \/>\n\u0628\u0647 \u062a\u0639\u0627\u062f\u0644 \u062f\u0631 \u0627\u0646\u062f\u06cc\u0634\u0647 \u0648 \u0639\u0645\u0644 \u0627\u0633\u0644\u0627\u0645\u06cc.<\/span><span dir=\"LTR\" style=\"font-size:20.0pt;\nline-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>\u2022 \u0635\u062f\u0648\u0631 \u062a\u0648\u0635\u06cc\u0647\u200c\u0647\u0627\u06cc \u06a9\u0627\u0631\u0628\u0631\u062f\u06cc \u0628\u0631\u0627\u06cc \u062a\u062f\u0648\u06cc\u0646 \u0628\u0631\u0646\u0627\u0645\u0647\u200c\u0647\u0627\u06cc<br \/>\n\u062f\u0631\u0633\u06cc \u0646\u0648\u06cc\u0646 \u0641\u0642\u0647\u06cc.<\/span><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;\nfont-family:&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>\u2022 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0622\u06af\u0627\u0647\u06cc \u0639\u0644\u0645\u06cc \u0627\u0632 \u0631\u0648\u06cc\u06a9\u0631\u062f \u0627\u0639\u062a\u062f\u0627\u0644 \u0648 \u0641\u0642\u0647 \u0645\u0639\u06cc\u0627\u0631.<\/span><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>\u2022 \u062a\u062f\u0648\u06cc\u0646 \u0627\u0633\u062a\u0631\u0627\u062a\u0698\u06cc\u200c\u0647\u0627\u06cc\u06cc \u0628\u0631\u0627\u06cc \u06a9\u0627\u0631\u0628\u0631\u062f \u062f\u0631 \u0632\u0646\u062f\u06af\u06cc \u0633\u06cc\u0627\u0633\u06cc\u060c<br \/>\n\u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0648 \u0627\u062c\u062a\u0645\u0627\u0639\u06cc.<\/span><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:\n115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><span dir=\"LTR\" style=\"font-size:20.0pt;\nline-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><b><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;;\ncolor:#0070C0\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>* \u0627\u0631\u06af\u0627\u0646 \u0647\u0627\u06cc \u0633\u0627\u0632\u0645\u0627\u0646\u062f\u0647\u06cc:<\/span><\/b><b><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;;\ncolor:#0070C0\"><o:p><\/o:p><\/span><\/b><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>\u2022 \u0627\u062a\u062d\u0627\u062f\u06cc\u0647 \u062c\u0647\u0627\u0646\u06cc \u0639\u0644\u0645\u0627\u06cc \u0645\u0633\u0644\u0645\u0627\u0646.<\/span><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>\u2022 \u062f\u0627\u0646\u0634\u06af\u0627\u0647 \u0648\u0642\u0641 \u0633\u0644\u0637\u0627\u0646 \u0645\u062d\u0645\u062f \u0627\u0644\u0641\u0627\u062a\u062d &#8211; \u062f\u0627\u0646\u0634\u06a9\u062f\u0647 \u0639\u0644\u0648\u0645<br \/>\n\u0627\u0633\u0644\u0627\u0645\u06cc. <\/span><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;\nfont-family:&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>&nbsp;* \u06a9\u0645\u06cc\u062a\u0647\u200c\u0647\u0627\u06cc<br \/>\n\u06a9\u0627\u0631\u06cc \u06a9\u0646\u0641\u0631\u0627\u0646\u0633:<\/span><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;\nfont-family:&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>\u2022 \u06a9\u0645\u06cc\u062a\u0647 \u0639\u0644\u0645\u06cc<\/span><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>\u2022 \u06a9\u0645\u06cc\u062a\u0647 \u0645\u0642\u062f\u0645\u0627\u062a\u06cc \u0648 \u0641\u0646\u06cc<\/span><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>\u2022 \u06a9\u0645\u06cc\u062a\u0647 \u062d\u0645\u0627\u06cc\u062a \u0648 \u062a\u0623\u0645\u06cc\u0646 \u0645\u0627\u0644\u06cc<\/span><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><span dir=\"LTR\" style=\"font-size:20.0pt;\nline-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><b><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;;\ncolor:#0070C0\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>* \u0633\u0627\u062e\u062a\u0627\u0631 \u0633\u0627\u0632\u0645\u0627\u0646\u06cc \u06a9\u0646\u0641\u0631\u0627\u0646\u0633:<\/span><\/b><b><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;;\ncolor:#0070C0\"><o:p><\/o:p><\/span><\/b><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>&#8211; \u0631\u0626\u06cc\u0633 \u06a9\u0646\u0641\u0631\u0627\u0646\u0633: \u062f\u06a9\u062a\u0631 \u0639\u0644\u06cc \u0645\u062d\u06cc \u0627\u0644\u062f\u06cc\u0646 \u0642\u0631\u0647 \u062f\u0627\u063a\u06cc<br \/>\n&#8211; \u0631\u0626\u06cc\u0633 \u0627\u062a\u062d\u0627\u062f\u06cc\u0647 \u062c\u0647\u0627\u0646\u06cc \u0639\u0644\u0645\u0627\u06cc \u0645\u0633\u0644\u0645\u0627\u0646.<\/span><span dir=\"LTR\" style=\"font-size:20.0pt;\nline-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>&#8211; \u0646\u0627\u0638\u0631 \u0639\u0645\u0648\u0645\u06cc \u06a9\u0646\u0641\u0631\u0627\u0646\u0633: \u062f\u06a9\u062a\u0631 \u0639\u0628\u062f \u0627\u0644\u0631\u062d\u0645\u0646 \u0627\u0648\u0632\u062f\u0645\u06cc\u0631<br \/>\n&#8211; \u0631\u0626\u06cc\u0633 \u062f\u0627\u0646\u0634\u06a9\u062f\u0647 \u0639\u0644\u0648\u0645 \u0627\u0633\u0644\u0627\u0645\u06cc \u062f\u0627\u0646\u0634\u06af\u0627\u0647 \u0648\u0642\u0641 \u0633\u0644\u0637\u0627\u0646 \u0645\u062d\u0645\u062f \u0641\u0627\u062a\u062d.<\/span><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><span dir=\"LTR\" style=\"font-size:20.0pt;\nline-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><b><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;;\ncolor:#0070C0\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>* \u06a9\u0645\u06cc\u062a\u0647\u200c\u0647\u0627\u06cc \u0633\u0627\u0632\u0645\u0627\u0646\u062f\u0647\u06cc:<\/span><\/b><b><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;;\ncolor:#0070C0\"><o:p><\/o:p><\/span><\/b><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>&#8211; \u06a9\u0645\u06cc\u062a\u0647 \u0639\u0644\u0645\u06cc<\/span><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>&#8211; \u06a9\u0645\u06cc\u062a\u0647 \u0645\u0642\u062f\u0645\u0627\u062a\u06cc \u0648 \u0641\u0646\u06cc<\/span><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>&#8211; \u06a9\u0645\u06cc\u062a\u0647 \u062d\u0645\u0627\u06cc\u062a \u0648 \u0628\u0648\u062f\u062c\u0647<\/span><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>&#8211; \u06a9\u0645\u06cc\u062a\u0647 \u0631\u0633\u0627\u0646\u0647<o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><span dir=\"LTR\" style=\"font-size:20.0pt;\nline-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><b><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;;\ncolor:#0070C0\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>* \u062a\u0627\u0631\u06cc\u062e\u200c\u0647\u0627\u06cc \u0645\u0647\u0645:<\/span><\/b><b><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;;\ncolor:#0070C0\"><o:p><\/o:p><\/span><\/b><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>\u2022 \u0627\u0637\u0644\u0627\u0639\u06cc\u0647 \u06a9\u0646\u0641\u0631\u0627\u0646\u0633: 10 \u0622\u0648\u0631\u06cc\u0644 2025.<\/span><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>\u2022 \u0622\u062e\u0631\u06cc\u0646 \u0645\u0647\u0644\u062a \u062f\u0631\u06cc\u0627\u0641\u062a \u0686\u06a9\u06cc\u062f\u0647 \u0645\u0642\u0627\u0644\u0627\u062a: 30 \u0622\u0648\u0631\u06cc\u0644<br \/>\n2025.<\/span><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:\n&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>\u2022 \u067e\u0627\u0633\u062e \u0628\u0647 \u0686\u06a9\u06cc\u062f\u0647\u200c\u0647\u0627\u06cc \u067e\u0630\u06cc\u0631\u0641\u062a\u0647 \u0634\u062f\u0647: 5 \u0645\u06cc 2025.<\/span><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>\u2022 \u0622\u062e\u0631\u06cc\u0646 \u0645\u0647\u0644\u062a \u0627\u0631\u0633\u0627\u0644 \u0645\u0642\u0627\u0644\u0627\u062a \u067e\u0698\u0648\u0647\u0634\u06cc \u06a9\u0627\u0645\u0644: 25 \u0645\u06cc<br \/>\n2025.<\/span><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:\n&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>\u2022 \u0627\u0637\u0644\u0627\u0639\u200c\u0631\u0633\u0627\u0646\u06cc \u0628\u0647 \u067e\u0698\u0648\u0647\u0634\u06af\u0631\u0627\u0646 \u0627\u0632 \u067e\u0630\u06cc\u0631\u0634 \u067e\u0698\u0648\u0647\u0634 \u0646\u0647\u0627\u06cc\u06cc:<br \/>\n5 \u0698\u0648\u0626\u0646 2025.<\/span><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;\nfont-family:&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>\u2022 \u062a\u0627\u0631\u06cc\u062e \u06a9\u0646\u0641\u0631\u0627\u0646\u0633: 21-22 \u0698\u0648\u0626\u0646 2025.<\/span><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><span dir=\"LTR\" style=\"font-size:20.0pt;\nline-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>* \u062a\u0648\u062c\u0647:<\/span><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span><span lang=\"AR-SA\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><span dir=\"RTL\"><\/span><span dir=\"RTL\"><\/span>&#8211; \u0644\u0637\u0641\u0627 \u0686\u06a9\u06cc\u062f\u0647 \u0648 \u062a\u062d\u0642\u06cc\u0642 \u0631\u0627 \u0628\u0647 \u0622\u062f\u0631\u0633 \u0627\u06cc\u0645\u06cc\u0644 \u0632\u06cc\u0631 \u0627\u0631\u0633\u0627\u0644<br \/>\n\u06a9\u0646\u06cc\u062f: <\/span><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:\n&quot;Sakkal Majalla&quot;\">nondes@fsm.edu.tr<\/span><span lang=\"AR-SA\" style=\"font-size:\n20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><span lang=\"AR-SA\" style=\"font-size:20.0pt;\nline-height:115%;font-family:&quot;Sakkal Majalla&quot;\">&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><b><span lang=\"AR-SA\" style=\"font-size:20.0pt;\nline-height:115%;font-family:&quot;Sakkal Majalla&quot;\">\u0640\u0640\u0640\u0640\u0640\u0640\u0640\u0640\u0640\u0640\u0640\u0640\u0640\u0640\u0640\u0640\u0640\u0640\u0640\u0640\u0640\u0640\u0640\u0640\u0640\u0640\u0640\u0640\u0640\u0640\u0640\u0640\u0640\u0640\u0640\u0640\u0640\u0640\u0640\u0640\u0640\u0640\u0640\u0640\u0640\u0640\u0640<o:p><\/o:p><\/span><\/b><\/p>\n<\/p>\n<p class=\"MsoNormal\" dir=\"RTL\" style=\"text-align: justify; unicode-bidi: embed;\"><b><span lang=\"AR-SA\" style=\"font-size:20.0pt;\nline-height:115%;font-family:&quot;Sakkal Majalla&quot;\">* \u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u062e\u0628\u0631 \u0628\u0627\u0644\u0644\u063a\u0629 \u0627\u0644\u0639\u0631\u0628\u064a\u0629\u060c \u0627\u0636\u063a\u0637<br \/>\n\u0639\u0644\u0649 \u0643\u0644\u0645\u0629 (<span style=\"color:#C00000\"><a href=\"https:\/\/iumsonline.org\/ar\/ContentDetails.aspx?ID=38915\" target=\"_blank\">\u0647\u0646\u0627<\/a><\/span>)&nbsp;<\/span><\/b><b><span dir=\"LTR\" style=\"font-size:20.0pt;line-height:115%;font-family:&quot;Sakkal Majalla&quot;\"><o:p><\/o:p><\/span><\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0627\u062a\u062d\u0627\u062f\u06cc\u0647 \u0648 \u062f\u0627\u0646\u0634\u06af\u0627\u0647 \u0633\u0644\u0637\u0627\u0646 \u0645\u062d\u0645\u062f \u0641\u0627\u062a\u062d \u0627\u0632 \u0647\u0645\u06a9\u0627\u0631\u06cc \u0639\u0644\u0645\u06cc \u0628\u0631\u0627\u06cc \u0628\u0631\u06af\u0632\u0627\u0631\u06cc \u0647\u0645\u0627\u06cc\u0634 \u00ab\u0641\u0642\u0647 \u0645\u0639\u06cc\u0627\u0631\u00bb \u062f\u0631 \u0698\u0648\u0626\u0646 \u0622\u06cc\u0646\u062f\u0647 \u062e\u0628\u0631 \u0645\u06cc\u200c\u062f\u0647\u0646\u062f<\/p>\n","protected":false},"author":0,"featured_media":89871,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[423],"tags":[],"class_list":["post-89623","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-union-activities-fa"],"acf":[],"_links":{"self":[{"href":"https:\/\/iumsonline.org\/fa\/wp-json\/wp\/v2\/posts\/89623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iumsonline.org\/fa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iumsonline.org\/fa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/iumsonline.org\/fa\/wp-json\/wp\/v2\/comments?post=89623"}],"version-history":[{"count":0,"href":"https:\/\/iumsonline.org\/fa\/wp-json\/wp\/v2\/posts\/89623\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iumsonline.org\/fa\/wp-json\/wp\/v2\/media\/89871"}],"wp:attachment":[{"href":"https:\/\/iumsonline.org\/fa\/wp-json\/wp\/v2\/media?parent=89623"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iumsonline.org\/fa\/wp-json\/wp\/v2\/categories?post=89623"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iumsonline.org\/fa\/wp-json\/wp\/v2\/tags?post=89623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}